{"id":21,"count":1,"description":"","link":"https:\/\/digitaldeals.biz\/fr\/category\/deals\/","name":"March\u00e9s","slug":"deals","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/digitaldeals.biz\/fr\/wp-json\/wp\/v2\/categories\/21","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/digitaldeals.biz\/fr\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/digitaldeals.biz\/fr\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/digitaldeals.biz\/fr\/wp-json\/wp\/v2\/posts?categories=21"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}